{"id":19,"count":3,"description":"","link":"http:\/\/www.fbs-carpet.com\/en\/service_cat\/%d8%b3%d8%ac%d8%a7%d8%af-%d9%85%d8%b3%d8%a7%d8%ac%d8%af\/","name":"mosque carpets","slug":"%d8%b3%d8%ac%d8%a7%d8%af-%d9%85%d8%b3%d8%a7%d8%ac%d8%af","taxonomy":"service_cat","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.fbs-carpet.com\/en\/wp-json\/wp\/v2\/service_cat\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.fbs-carpet.com\/en\/wp-json\/wp\/v2\/service_cat"}],"about":[{"href":"http:\/\/www.fbs-carpet.com\/en\/wp-json\/wp\/v2\/taxonomies\/service_cat"}],"wp:post_type":[{"href":"http:\/\/www.fbs-carpet.com\/en\/wp-json\/wp\/v2\/service?service_cat=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}